{"id":262,"date":"2018-05-28T02:41:22","date_gmt":"2018-05-28T06:41:22","guid":{"rendered":"https:\/\/www.floridacitrus.quebec\/grapefruit\/?post_type=fdoc-recipe&#038;p=262"},"modified":"2024-06-15T09:47:37","modified_gmt":"2024-06-15T13:47:37","slug":"poulet-grille-et-asperges-avec-sauce-au-pamplemousse-rose-et-a-la-moutarde","status":"publish","type":"fdoc-recipe","link":"https:\/\/www.floridacitrus.quebec\/grapefruit\/recipes\/poulet-grille-et-asperges-avec-sauce-au-pamplemousse-rose-et-a-la-moutarde\/","title":{"rendered":"Poulet grill\u00e9 et asperges avec sauce au pamplemousse rose et \u00e0 la moutarde"},"content":{"rendered":"\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-fdoc-recipe-ingredients\">\r\n<li>2 (110\u00a0g) blancs de poulet d\u00e9soss\u00e9s sans la peau<\/li>\r\n<li>225\u00a0g d&rsquo;asperges<\/li>\r\n<li>1 pamplemousse de la Floride rose, entier<\/li>\r\n<li>250\u00a0ml de jus de pamplemousse de la Floride rose<\/li>\r\n<li>250\u00a0ml de bouillon de volaille sans mati\u00e8re grasse et \u00e0 teneur r\u00e9duite en sel<\/li>\r\n<li>1\/2 d&rsquo;oignon blanc de taille moyenne finement \u00e9minc\u00e9<\/li>\r\n<li>1 cuill\u00e8re \u00e0 th\u00e9 d&rsquo;huile d&rsquo;olive<\/li>\r\n<li>1 cuill\u00e8re \u00e0 th\u00e9 de moutarde de Dijon pr\u00e9par\u00e9e<\/li>\r\n<li>1\/2 cuill\u00e8re \u00e0 th\u00e9 de moutarde moulue<\/li>\r\n<li>1\/2 cuill\u00e8re \u00e0 th\u00e9 de thym s\u00e9ch\u00e9<\/li>\r\n<li>Sel et poivre<\/li>\r\n<li>Brins de thym ou persil plat \u00e9minc\u00e9 pour la d\u00e9coration<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n\r\n\r\n<div class=\"wp-block-fdoc-recipe-instructions\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>Pelez le pamplemousse et d\u00e9tachez les quartiers. R\u00e9servez.<\/p>\r\n<p><br \/>Pour la sauce, faites chauffer l&rsquo;huile dans une sauteuse antiadh\u00e9sive. Ajoutez l&rsquo;oignon et faites sauter \u00e0 feu moyen pendant environ cinq minutes, ou jusqu&rsquo;\u00e0 ce que les oignons soient ramollis, mais pas roussis. Ajoutez le jus de pamplemousse, le bouillon, la moutarde moulue et le thym. Portez \u00e0 \u00e9bullition et r\u00e9duisez ensuite \u00e0 feu doux.Laissez mijoter jusqu&rsquo;\u00e0 ce que la sauce ait r\u00e9duit de moiti\u00e9. Ne faites pas trop cuire ou la sauce peut devenir am\u00e8re. Retirez du feu et transf\u00e9rez d\u00e9licatement la sauce dans un mixeur ou un robot culinaire. Ajoutez la moutarde pr\u00e9par\u00e9e et mixez ou passez au robot jusqu&rsquo;\u00e0 obtention d&rsquo;une consistance homog\u00e8ne, puis remettez la sauce dans la po\u00eale. Salez et poivrez selon votre go\u00fbt. Couvrez et gardez au chaud.<\/p>\r\n<p><br \/>Faites griller le poulet et les asperges sur des charbons ardents jusqu&rsquo;\u00e0 ce qu&rsquo;ils soient bien cuits. Disposez le poulet, les asperges et les quartiers de pamplemousse dans deux assiettes chaudes. Versez la sauce. Garnissez de brins de thym ou de persil. Servez avec du riz sauvage ou du couscous de bl\u00e9 complet.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ingr\u00e9dients Pr\u00e9paration<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"fdoc-citrus-type":[19],"fdoc-recipe-method":[],"fdoc-recipe-diet":[],"fdoc-health-category":[2,3,23],"fdoc-recipe-lifestyle":[],"fdoc-recipe-course":[44],"fdoc-recipe-cuisine":[],"fdoc-recipe-ingredient":[],"fdoc-recipe-keyword":[211,212,193],"class_list":["post-262","fdoc-recipe","type-fdoc-recipe","status-publish","hentry","fdoc-citrus-type-grapefruit-juice","fdoc-health-category-anti-inflammatory","fdoc-health-category-antioxidant-rich","fdoc-health-category-heart-health","fdoc-recipe-course-side-dish"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe"}],"about":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/types\/fdoc-recipe"}],"version-history":[{"count":6,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/262\/revisions"}],"predecessor-version":[{"id":3180,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/262\/revisions\/3180"}],"wp:attachment":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"fdoc-citrus-type","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-citrus-type?post=262"},{"taxonomy":"fdoc-recipe-method","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-method?post=262"},{"taxonomy":"fdoc-recipe-diet","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-diet?post=262"},{"taxonomy":"fdoc-health-category","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-health-category?post=262"},{"taxonomy":"fdoc-recipe-lifestyle","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-lifestyle?post=262"},{"taxonomy":"fdoc-recipe-course","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-course?post=262"},{"taxonomy":"fdoc-recipe-cuisine","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-cuisine?post=262"},{"taxonomy":"fdoc-recipe-ingredient","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-ingredient?post=262"},{"taxonomy":"fdoc-recipe-keyword","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-keyword?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}