{"id":263,"date":"2018-05-28T02:44:27","date_gmt":"2018-05-28T06:44:27","guid":{"rendered":"https:\/\/www.floridacitrus.quebec\/grapefruit\/?post_type=fdoc-recipe&#038;p=263"},"modified":"2024-06-16T02:21:08","modified_gmt":"2024-06-16T06:21:08","slug":"galette-grillee-au-poulet-et-pamplemousse-de-floride","status":"publish","type":"fdoc-recipe","link":"https:\/\/www.floridacitrus.quebec\/grapefruit\/recipes\/galette-grillee-au-poulet-et-pamplemousse-de-floride\/","title":{"rendered":"Galette grill\u00e9e au poulet et pamplemousse de Floride"},"content":{"rendered":"\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-fdoc-recipe-ingredients\">\r\n<li>1 pamplemousse de Floride pel\u00e9 et coup\u00e9 en 8 quartiers<\/li>\r\n<li>1 pain Naan<\/li>\r\n<li>2 Cs d&rsquo;huile d&rsquo;olive<\/li>\r\n<li>115\u00a0g de mozzarella fra\u00eeche coup\u00e9e en morceaux<\/li>\r\n<li>\u00bd tasse (70 g) de poulet sauce BBQ cuit coup\u00e9 en morceaux<\/li>\r\n<li>2 tranches de prosciutto coup\u00e9 en morceaux<\/li>\r\n<li>\u00bd avocat pel\u00e9, d\u00e9noyaut\u00e9 et coup\u00e9 en morceaux<\/li>\r\n<li>Poign\u00e9e de roquette fra\u00eechement lav\u00e9e<\/li>\r\n<li>Poign\u00e9e de cresson fra\u00eechement lav\u00e9<\/li>\r\n<li>Sel et poivre<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Ingr\u00e9dients de la sauce piquante au miel\u00a0:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-fdoc-recipe-ingredients\">\r\n<li>2 Cs de miel<\/li>\r\n<li>1 piment rouge coup\u00e9 en petits d\u00e9s<\/li>\r\n<li>1 gousse d&rsquo;ail coup\u00e9e en petits d\u00e9s<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n\r\n\r\n<div class=\"wp-block-fdoc-recipe-instructions\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__title\">\u00c9tape\u00a01<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>Pr\u00e9chauffez le four \u00e0 200\u00a0\u00b0C. Recouvrez une plaque de cuisson de papier sulfuris\u00e9 et r\u00e9servez.Dans un petit bol, m\u00e9langez les ingr\u00e9dients de la sauce et r\u00e9servez.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__title\">\u00c9tape\u00a02<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>Faites griller les pains 4 minutes de chaque c\u00f4t\u00e9 et transf\u00e9rez-les sur la plaque de cuisson.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__title\">\u00c9tape\u00a03<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>Faites chauffer le gril \u00e0 haute temp\u00e9rature.Dans un bol moyen, m\u00e9langez le pamplemousse coup\u00e9 en quartiers avec l&rsquo;huile d&rsquo;olive.Faites griller le pamplemousse de Floride 1 minute de chaque c\u00f4t\u00e9 et r\u00e9servez.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__title\">\u00c9tape\u00a04<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>R\u00e9partissez \u00e9galement la mozzarella, le pamplemousse de Floride grill\u00e9, le poulet, le prosciutto et l&rsquo;avocat sur les pains, salez et poivrez.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step\">\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__title\">\u00c9tape\u00a05<\/div>\r\n<div class=\"wp-block-fdoc-recipe-instructions-step__text\">\r\n<div>\r\n<p>Faites cuire les galettes 6 minutes, jusqu&rsquo;\u00e0 ce que le fromage ait fondu.Terminez avec de la roquette fra\u00eeche et du cresson.Arrosez de sauce piquante au miel.Servez ti\u00e8de.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ingr\u00e9dients Ingr\u00e9dients de la sauce piquante au miel\u00a0: Pr\u00e9paration<\/p>\n","protected":false},"featured_media":264,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"fdoc-citrus-type":[18],"fdoc-recipe-method":[],"fdoc-recipe-diet":[],"fdoc-health-category":[2,23],"fdoc-recipe-lifestyle":[],"fdoc-recipe-course":[4,13],"fdoc-recipe-cuisine":[],"fdoc-recipe-ingredient":[],"fdoc-recipe-keyword":[209,210,193],"class_list":["post-263","fdoc-recipe","type-fdoc-recipe","status-publish","has-post-thumbnail","hentry","fdoc-citrus-type-grapefruit","fdoc-health-category-anti-inflammatory","fdoc-health-category-heart-health","fdoc-recipe-course-appetizer","fdoc-recipe-course-entree"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe"}],"about":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/types\/fdoc-recipe"}],"version-history":[{"count":5,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/263\/revisions"}],"predecessor-version":[{"id":3309,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/263\/revisions\/3309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media\/264"}],"wp:attachment":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"fdoc-citrus-type","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-citrus-type?post=263"},{"taxonomy":"fdoc-recipe-method","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-method?post=263"},{"taxonomy":"fdoc-recipe-diet","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-diet?post=263"},{"taxonomy":"fdoc-health-category","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-health-category?post=263"},{"taxonomy":"fdoc-recipe-lifestyle","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-lifestyle?post=263"},{"taxonomy":"fdoc-recipe-course","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-course?post=263"},{"taxonomy":"fdoc-recipe-cuisine","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-cuisine?post=263"},{"taxonomy":"fdoc-recipe-ingredient","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-ingredient?post=263"},{"taxonomy":"fdoc-recipe-keyword","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-keyword?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}