{"id":2943,"date":"2024-04-28T10:54:30","date_gmt":"2024-04-28T14:54:30","guid":{"rendered":"https:\/\/www.floridacitrus.quebec\/grapefruit\/?post_type=fdoc-recipe&#038;p=2943"},"modified":"2024-06-15T13:43:08","modified_gmt":"2024-06-15T17:43:08","slug":"cotelettes-de-porc-au-pamplemousse-de-la-floride-au-gingembre-et-au-piment-chili","status":"publish","type":"fdoc-recipe","link":"https:\/\/www.floridacitrus.quebec\/grapefruit\/recipes\/cotelettes-de-porc-au-pamplemousse-de-la-floride-au-gingembre-et-au-piment-chili\/","title":{"rendered":"C\u00f4telettes de porc au pamplemousse de la Floride, au gingembre et au piment chili"},"content":{"rendered":"\r\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\r\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.floridacitrus.ca\/grapefruit\/recipes\/chili-and-ginger-pork-with-florida-grapefruit\/\" target=\"_blank\" rel=\"noreferrer noopener\">English<\/a><\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Cette recette de c\u00f4telettes de porc relev\u00e9e de piment de chili et de gingembre est riche en saveurs! Donne 2 portions<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-fdoc-recipe-ingredients\">\r\n<li>2\u00a0pamplemousses de la Floride<\/li>\r\n<li>2\u00a0c\u00f4telettes de porc<\/li>\r\n<li>2\u00a0cuill\u00e8res \u00e0 table (30\u00a0ml) d\u2019huile d\u2019olive<\/li>\r\n<li>Sel et poivre<\/li>\r\n<li>1\u00a0cuill\u00e8re \u00e0 table (15\u00a0ml) de graines de fenouil<\/li>\r\n<li>2\u00a0cuill\u00e8res \u00e0 table (30 ml ou 30\u00a0g) de beurre<\/li>\r\n<li>1\u00a0pouce (3\u00a0cm) de gingembre frais, tranch\u00e9 mince<\/li>\r\n<li>1\u00a0piment chili<\/li>\r\n<li>1\u00a0botte de chou fris\u00e9<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n<p>Assaisonner les c\u00f4telettes de porc avec l\u2019huile d\u2019olive, le sel, le poivre et les graines de fenouil. Faire cuire les c\u00f4telettes dans une po\u00eale \u00e0 frire pr\u00e9chauff\u00e9e sur un feu moyen-\u00e9lev\u00e9 jusqu\u2019\u00e0 ce qu\u2019elles soient dor\u00e9es, soit environ 5\u00a0minutes de chaque c\u00f4t\u00e9. Pendant ce temps, trancher le gingembre et le piment de chili et les ajouter \u00e0 la po\u00eale \u00e0 frire. Laver la pelure du pamplemousse de la Floride et la zester au-dessus des c\u00f4telettes pendant la cuisson. Couper le pamplemousse en deux et en presser le jus directement dans la po\u00eale. Ajouter le beurre et le chou fris\u00e9 dans la po\u00eale et continuer la cuisson pendant 3-4\u00a0minutes jusqu\u2019\u00e0 ce que les c\u00f4telettes soient cuites et que le chou fris\u00e9 ait ramolli. Servir et d\u00e9guster!<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Cette recette de c\u00f4telettes de porc relev\u00e9e de piment de chili et de gingembre est riche en saveurs! Donne 2 portions Ingr\u00e9dients Pr\u00e9paration Assaisonner les c\u00f4telettes de porc avec l\u2019huile d\u2019olive, le sel, le poivre et les graines de fenouil. Faire cuire les c\u00f4telettes dans une po\u00eale \u00e0 frire pr\u00e9chauff\u00e9e sur un feu moyen-\u00e9lev\u00e9 jusqu\u2019\u00e0&#8230;<\/p>\n","protected":false},"featured_media":2948,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"fdoc-citrus-type":[],"fdoc-recipe-method":[],"fdoc-recipe-diet":[],"fdoc-health-category":[26,31,24,3,17],"fdoc-recipe-lifestyle":[],"fdoc-recipe-course":[310],"fdoc-recipe-cuisine":[],"fdoc-recipe-ingredient":[],"fdoc-recipe-keyword":[],"class_list":["post-2943","fdoc-recipe","type-fdoc-recipe","status-publish","has-post-thumbnail","hentry","fdoc-health-category-kid-friendly","fdoc-health-category-low-sugar","fdoc-health-category-high-protein","fdoc-health-category-antioxidant-rich","fdoc-health-category-gluten-free","fdoc-recipe-course-plat-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/2943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe"}],"about":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/types\/fdoc-recipe"}],"version-history":[{"count":6,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/2943\/revisions"}],"predecessor-version":[{"id":3260,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/2943\/revisions\/3260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media\/2948"}],"wp:attachment":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media?parent=2943"}],"wp:term":[{"taxonomy":"fdoc-citrus-type","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-citrus-type?post=2943"},{"taxonomy":"fdoc-recipe-method","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-method?post=2943"},{"taxonomy":"fdoc-recipe-diet","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-diet?post=2943"},{"taxonomy":"fdoc-health-category","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-health-category?post=2943"},{"taxonomy":"fdoc-recipe-lifestyle","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-lifestyle?post=2943"},{"taxonomy":"fdoc-recipe-course","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-course?post=2943"},{"taxonomy":"fdoc-recipe-cuisine","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-cuisine?post=2943"},{"taxonomy":"fdoc-recipe-ingredient","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-ingredient?post=2943"},{"taxonomy":"fdoc-recipe-keyword","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-keyword?post=2943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}