{"id":856,"date":"2022-06-24T16:47:59","date_gmt":"2022-06-24T20:47:59","guid":{"rendered":"https:\/\/www.floridacitrus.quebec\/grapefruit\/?post_type=fdoc-recipe&#038;p=856"},"modified":"2024-06-15T14:04:30","modified_gmt":"2024-06-15T18:04:30","slug":"frose-au-pamplemousse","status":"publish","type":"fdoc-recipe","link":"https:\/\/www.floridacitrus.quebec\/grapefruit\/recipes\/frose-au-pamplemousse\/","title":{"rendered":"Fros\u00e9 au pamplemousse"},"content":{"rendered":"\r\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\r\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.floridacitrus.ca\/grapefruit\/\/recipes\/frose-grapefruit-cocktail\/\">ENGLISH<\/a><\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-fdoc-recipe-ingredients\">\r\n<li>1 pamplemousse ruby \u00e0 peau et \u00e0 pulpe rouge de la Floride<\/li>\r\n<li>1\u00bd tasse (375\u00a0ml) de gla\u00e7ons<\/li>\r\n<li>\u00bd tasse (125\u00a0ml) de vin ros\u00e9<\/li>\r\n<li>Menthe, pour la garniture<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n<p>Couper le pamplemousse ruby \u00e0 peau et \u00e0 pulpe rouge de la Floride en deux. R\u00e9server une moiti\u00e9 pour la garniture.<\/p>\r\n\r\n\r\n\r\n<p>Prendre l&rsquo;autre moiti\u00e9 du pamplemousse et presser son jus jusqu&rsquo;\u00e0 ce que vous obteniez \u00bd tasse (125\u00a0ml) de jus.<\/p>\r\n\r\n\r\n\r\n<p>M\u00e9langer la glace, le ros\u00e9 et le jus de pamplemousse ruby \u00e0 peau et \u00e0 pulpe rouge de la Floride dans un m\u00e9langeur jusqu&rsquo;\u00e0 l&rsquo;obtention d&rsquo;un m\u00e9lange homog\u00e8ne.<\/p>\r\n\r\n\r\n\r\n<p>Verser dans un verre \u00e0 cocktail et garnir avec des feuilles de menthe et des tranches de pamplemousse de la Floride.<\/p>\r\n\r\n\r\n\r\n<p>Conseils utiles :<\/p>\r\n\r\n\r\n\r\n<p>Utiliser du sirop simple et entourer le verre de sucre pour sucrer la boisson cocktail.<\/p>\r\n\r\n\r\n\r\n<p>Pour plus de saveur, ajouter la menthe hach\u00e9e avant de m\u00e9langer.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ingr\u00e9dients Pr\u00e9paration Couper le pamplemousse ruby \u00e0 peau et \u00e0 pulpe rouge de la Floride en deux. R\u00e9server une moiti\u00e9 pour la garniture. Prendre l&rsquo;autre moiti\u00e9 du pamplemousse et presser son jus jusqu&rsquo;\u00e0 ce que vous obteniez \u00bd tasse (125\u00a0ml) de jus. M\u00e9langer la glace, le ros\u00e9 et le jus de pamplemousse ruby \u00e0 peau&#8230;<\/p>\n","protected":false},"featured_media":857,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"fdoc-citrus-type":[19,18],"fdoc-recipe-method":[],"fdoc-recipe-diet":[],"fdoc-health-category":[3,38,51],"fdoc-recipe-lifestyle":[],"fdoc-recipe-course":[12],"fdoc-recipe-cuisine":[],"fdoc-recipe-ingredient":[],"fdoc-recipe-keyword":[79,78],"class_list":["post-856","fdoc-recipe","type-fdoc-recipe","status-publish","has-post-thumbnail","hentry","fdoc-citrus-type-grapefruit-juice","fdoc-citrus-type-grapefruit","fdoc-health-category-antioxidant-rich","fdoc-health-category-potassium-rich","fdoc-health-category-vitamin-c-rich","fdoc-recipe-course-drink"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe"}],"about":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/types\/fdoc-recipe"}],"version-history":[{"count":7,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/856\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe\/856\/revisions\/3281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media\/857"}],"wp:attachment":[{"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/media?parent=856"}],"wp:term":[{"taxonomy":"fdoc-citrus-type","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-citrus-type?post=856"},{"taxonomy":"fdoc-recipe-method","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-method?post=856"},{"taxonomy":"fdoc-recipe-diet","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-diet?post=856"},{"taxonomy":"fdoc-health-category","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-health-category?post=856"},{"taxonomy":"fdoc-recipe-lifestyle","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-lifestyle?post=856"},{"taxonomy":"fdoc-recipe-course","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-course?post=856"},{"taxonomy":"fdoc-recipe-cuisine","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-cuisine?post=856"},{"taxonomy":"fdoc-recipe-ingredient","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-ingredient?post=856"},{"taxonomy":"fdoc-recipe-keyword","embeddable":true,"href":"https:\/\/www.floridacitrus.quebec\/grapefruit\/wp-json\/wp\/v2\/fdoc-recipe-keyword?post=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}